{"id":4201,"date":"2023-02-16T06:51:35","date_gmt":"2023-02-16T06:51:35","guid":{"rendered":"https:\/\/mcpedl.in\/?p=4201"},"modified":"2023-02-16T07:00:14","modified_gmt":"2023-02-16T07:00:14","slug":"the-best-minecraft-pe-version","status":"publish","type":"post","link":"https:\/\/mcpedl.in\/zh\/the-best-minecraft-pe-version\/","title":{"rendered":"\u6700\u597d\u7684 Minecraft PE \u7248\u672c"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":4121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[137],"tags":[],"_links":{"self":[{"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/posts\/4201"}],"collection":[{"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/comments?post=4201"}],"version-history":[{"count":3,"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/posts\/4201\/revisions"}],"predecessor-version":[{"id":4205,"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/posts\/4201\/revisions\/4205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/media\/4121"}],"wp:attachment":[{"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/media?parent=4201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/categories?post=4201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/tags?post=4201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}