{"id":3948,"date":"2022-10-19T19:38:49","date_gmt":"2022-10-19T19:38:49","guid":{"rendered":"https:\/\/mcpedl.in\/?page_id=3948"},"modified":"2025-05-27T16:18:23","modified_gmt":"2025-05-27T16:18:23","slug":"better-foliage-mod-for-minecraft-pe-download","status":"publish","type":"page","link":"https:\/\/mcpedl.in\/zh\/better-foliage-mod-for-minecraft-pe-download\/","title":{"rendered":"Better Foliage Mod for Minecraft PE download"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/pages\/3948"}],"collection":[{"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/comments?post=3948"}],"version-history":[{"count":1,"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/pages\/3948\/revisions"}],"predecessor-version":[{"id":3953,"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/pages\/3948\/revisions\/3953"}],"wp:attachment":[{"href":"https:\/\/mcpedl.in\/zh\/wp-json\/wp\/v2\/media?parent=3948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}